{"id":2042,"date":"2023-11-09T13:07:06","date_gmt":"2023-11-09T12:07:06","guid":{"rendered":"https:\/\/louisdelhaize.be\/mentions-legales\/"},"modified":"2025-06-23T10:21:06","modified_gmt":"2025-06-23T08:21:06","slug":"wettelijke-vermeldingen","status":"publish","type":"page","link":"https:\/\/louisdelhaize.be\/nl\/wettelijke-vermeldingen\/","title":{"rendered":"Wettelijke vermeldingen"},"content":{"rendered":"\r\n<h2 class=\"wp-block-heading\">Qui sommes-nous\u00a0?<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>L\u2019adresse de notre site Web est\u00a0: https:\/\/louisdelhaize.be.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Commentaires<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Quand vous laissez un commentaire sur notre site web, les donn\u00e9es inscrites dans le formulaire de commentaire, mais aussi votre adresse IP et l\u2019agent utilisateur de votre navigateur sont collect\u00e9s pour nous aider \u00e0 la d\u00e9tection des commentaires ind\u00e9sirables.<\/p>\r\n\r\n\r\n\r\n<p>Une cha\u00eene anonymis\u00e9e cr\u00e9\u00e9e \u00e0 partir de votre adresse de messagerie (\u00e9galement appel\u00e9e hash) peut \u00eatre envoy\u00e9e au service Gravatar pour v\u00e9rifier si vous utilisez ce dernier. Les clauses de confidentialit\u00e9 du service Gravatar sont disponibles ici\u00a0: https:\/\/automattic.com\/privacy\/. Apr\u00e8s validation de votre commentaire, votre photo de profil sera visible publiquement \u00e0 cot\u00e9 de votre commentaire.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">M\u00e9dias<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Si vous \u00eates un utilisateur ou une utilisatrice enregistr\u00e9\u00b7e et que vous t\u00e9l\u00e9versez des images sur le site web, nous vous conseillons d\u2019\u00e9viter de t\u00e9l\u00e9verser des images contenant des donn\u00e9es EXIF de coordonn\u00e9es GPS. Les visiteurs de votre site web peuvent t\u00e9l\u00e9charger et extraire des donn\u00e9es de localisation depuis ces images.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Cookies<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Si vous d\u00e9posez un commentaire sur notre site, il vous sera propos\u00e9 d\u2019enregistrer votre nom, adresse de messagerie et site web dans des cookies. C\u2019est uniquement pour votre confort afin de ne pas avoir \u00e0 saisir ces informations si vous d\u00e9posez un autre commentaire plus tard. Ces cookies expirent au bout d\u2019un an.<\/p>\r\n\r\n\r\n\r\n<p>Si vous vous rendez sur la page de connexion, un cookie temporaire sera cr\u00e9\u00e9 afin de d\u00e9terminer si votre navigateur accepte les cookies. Il ne contient pas de donn\u00e9es personnelles et sera supprim\u00e9 automatiquement \u00e0 la fermeture de votre navigateur.<\/p>\r\n\r\n\r\n\r\n<p>Lorsque vous vous connecterez, nous mettrons en place un certain nombre de cookies pour enregistrer vos informations de connexion et vos pr\u00e9f\u00e9rences d\u2019\u00e9cran. La dur\u00e9e de vie d\u2019un cookie de connexion est de deux jours, celle d\u2019un cookie d\u2019option d\u2019\u00e9cran est d\u2019un an. Si vous cochez \u00ab\u00a0Se souvenir de moi\u00a0\u00bb, votre cookie de connexion sera conserv\u00e9 pendant deux semaines. Si vous vous d\u00e9connectez de votre compte, le cookie de connexion sera effac\u00e9.<\/p>\r\n\r\n\r\n\r\n<p>En modifiant ou en publiant une publication, un cookie suppl\u00e9mentaire sera enregistr\u00e9 dans votre navigateur. Ce cookie ne comprend aucune donn\u00e9e personnelle. Il indique simplement l\u2019ID de la publication que vous venez de modifier. Il expire au bout d\u2019un jour.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Contenu embarqu\u00e9 depuis d\u2019autres sites<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Les articles de ce site peuvent inclure des contenus int\u00e9gr\u00e9s (par exemple des vid\u00e9os, images, articles\u2026). Le contenu int\u00e9gr\u00e9 depuis d\u2019autres sites se comporte de la m\u00eame mani\u00e8re que si le visiteur se rendait sur cet autre site.<\/p>\r\n\r\n\r\n\r\n<p>Ces sites web pourraient collecter des donn\u00e9es sur vous, utiliser des cookies, embarquer des outils de suivis tiers, suivre vos interactions avec ces contenus embarqu\u00e9s si vous disposez d\u2019un compte connect\u00e9 sur leur site web.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Utilisation et transmission de vos donn\u00e9es personnelles<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Si vous demandez une r\u00e9initialisation de votre mot de passe, votre adresse IP sera incluse dans l\u2019e-mail de r\u00e9initialisation.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Dur\u00e9es de stockage de vos donn\u00e9es<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Si vous laissez un commentaire, le commentaire et ses m\u00e9tadonn\u00e9es sont conserv\u00e9s ind\u00e9finiment. Cela permet de reconna\u00eetre et approuver automatiquement les commentaires suivants au lieu de les laisser dans la file de mod\u00e9ration.<\/p>\r\n\r\n\r\n\r\n<p>Pour les utilisateurs et utilisatrices qui s\u2019enregistrent sur notre site (si cela est possible), nous stockons \u00e9galement les donn\u00e9es personnelles indiqu\u00e9es dans leur profil. Tous les utilisateurs et utilisatrices peuvent voir, modifier ou supprimer leurs informations personnelles \u00e0 tout moment (\u00e0 l\u2019exception de leur nom d\u2019utilisateur\u00b7ice). Les gestionnaires du site peuvent aussi voir et modifier ces informations.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Les droits que vous avez sur vos donn\u00e9es<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Si vous avez un compte ou si vous avez laiss\u00e9 des commentaires sur le site, vous pouvez demander \u00e0 recevoir un fichier contenant toutes les donn\u00e9es personnelles que nous poss\u00e9dons \u00e0 votre sujet, incluant celles que vous nous avez fournies. Vous pouvez \u00e9galement demander la suppression des donn\u00e9es personnelles vous concernant. Cela ne prend pas en compte les donn\u00e9es stock\u00e9es \u00e0 des fins administratives, l\u00e9gales ou pour des raisons de s\u00e9curit\u00e9.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Where your data is sent<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Les commentaires des visiteurs peuvent \u00eatre v\u00e9rifi\u00e9s \u00e0 l\u2019aide d\u2019un service automatis\u00e9 de d\u00e9tection des commentaires ind\u00e9sirables.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Qui sommes-nous\u00a0? Texte sugg\u00e9r\u00e9\u00a0: L\u2019adresse de notre site Web est\u00a0: https:\/\/louisdelhaize.be. Commentaires Texte sugg\u00e9r\u00e9\u00a0: Quand vous laissez un commentaire sur notre site web, les donn\u00e9es inscrites dans le formulaire de commentaire, mais aussi votre adresse IP et l\u2019agent utilisateur de votre navigateur sont collect\u00e9s pour nous aider \u00e0 la d\u00e9tection des commentaires ind\u00e9sirables. Une cha\u00eene &hellip; <a href=\"https:\/\/louisdelhaize.be\/nl\/wettelijke-vermeldingen\/\">Continued<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-page.blade.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-2042","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wettelijke vermeldingen - Louis Delhaize<\/title>\n<meta name=\"description\" content=\"Wettelijke vermeldingen: Delfood heeft alles in het werk gesteld om het priv\u00e9leven van alle personen die zich op onze internetsite aansluiten te respecteren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/louisdelhaize.be\/nl\/wettelijke-vermeldingen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wettelijke vermeldingen - Louis Delhaize\" \/>\n<meta property=\"og:description\" content=\"Wettelijke vermeldingen: Delfood heeft alles in het werk gesteld om het priv\u00e9leven van alle personen die zich op onze internetsite aansluiten te respecteren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/louisdelhaize.be\/nl\/wettelijke-vermeldingen\/\" \/>\n<meta property=\"og:site_name\" content=\"Louis Delhaize\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-23T08:21:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/louisdelhaize.be\/nl\/wettelijke-vermeldingen\/\",\"url\":\"https:\/\/louisdelhaize.be\/nl\/wettelijke-vermeldingen\/\",\"name\":\"Wettelijke vermeldingen - Louis Delhaize\",\"isPartOf\":{\"@id\":\"https:\/\/louisdelhaize.be\/nl\/#website\"},\"datePublished\":\"2023-11-09T12:07:06+00:00\",\"dateModified\":\"2025-06-23T08:21:06+00:00\",\"description\":\"Wettelijke vermeldingen: Delfood heeft alles in het werk gesteld om het priv\u00e9leven van alle personen die zich op onze internetsite aansluiten te respecteren.\",\"breadcrumb\":{\"@id\":\"https:\/\/louisdelhaize.be\/nl\/wettelijke-vermeldingen\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/louisdelhaize.be\/nl\/wettelijke-vermeldingen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/louisdelhaize.be\/nl\/wettelijke-vermeldingen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/louisdelhaize.be\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wettelijke vermeldingen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/louisdelhaize.be\/nl\/#website\",\"url\":\"https:\/\/louisdelhaize.be\/nl\/\",\"name\":\"Louis Delhaize\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/louisdelhaize.be\/nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/louisdelhaize.be\/nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/louisdelhaize.be\/nl\/#organization\",\"name\":\"Louis Delhaize\",\"url\":\"https:\/\/louisdelhaize.be\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/louisdelhaize.be\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/louisdelhaize.be\/app\/uploads\/2023\/08\/logo-louis-delhaize.svg\",\"contentUrl\":\"https:\/\/louisdelhaize.be\/app\/uploads\/2023\/08\/logo-louis-delhaize.svg\",\"width\":1,\"height\":1,\"caption\":\"Louis Delhaize\"},\"image\":{\"@id\":\"https:\/\/louisdelhaize.be\/nl\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wettelijke vermeldingen - Louis Delhaize","description":"Wettelijke vermeldingen: Delfood heeft alles in het werk gesteld om het priv\u00e9leven van alle personen die zich op onze internetsite aansluiten te respecteren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/louisdelhaize.be\/nl\/wettelijke-vermeldingen\/","og_locale":"nl_NL","og_type":"article","og_title":"Wettelijke vermeldingen - Louis Delhaize","og_description":"Wettelijke vermeldingen: Delfood heeft alles in het werk gesteld om het priv\u00e9leven van alle personen die zich op onze internetsite aansluiten te respecteren.","og_url":"https:\/\/louisdelhaize.be\/nl\/wettelijke-vermeldingen\/","og_site_name":"Louis Delhaize","article_modified_time":"2025-06-23T08:21:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/louisdelhaize.be\/nl\/wettelijke-vermeldingen\/","url":"https:\/\/louisdelhaize.be\/nl\/wettelijke-vermeldingen\/","name":"Wettelijke vermeldingen - Louis Delhaize","isPartOf":{"@id":"https:\/\/louisdelhaize.be\/nl\/#website"},"datePublished":"2023-11-09T12:07:06+00:00","dateModified":"2025-06-23T08:21:06+00:00","description":"Wettelijke vermeldingen: Delfood heeft alles in het werk gesteld om het priv\u00e9leven van alle personen die zich op onze internetsite aansluiten te respecteren.","breadcrumb":{"@id":"https:\/\/louisdelhaize.be\/nl\/wettelijke-vermeldingen\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/louisdelhaize.be\/nl\/wettelijke-vermeldingen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/louisdelhaize.be\/nl\/wettelijke-vermeldingen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/louisdelhaize.be\/nl\/"},{"@type":"ListItem","position":2,"name":"Wettelijke vermeldingen"}]},{"@type":"WebSite","@id":"https:\/\/louisdelhaize.be\/nl\/#website","url":"https:\/\/louisdelhaize.be\/nl\/","name":"Louis Delhaize","description":"","publisher":{"@id":"https:\/\/louisdelhaize.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/louisdelhaize.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/louisdelhaize.be\/nl\/#organization","name":"Louis Delhaize","url":"https:\/\/louisdelhaize.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/louisdelhaize.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/louisdelhaize.be\/app\/uploads\/2023\/08\/logo-louis-delhaize.svg","contentUrl":"https:\/\/louisdelhaize.be\/app\/uploads\/2023\/08\/logo-louis-delhaize.svg","width":1,"height":1,"caption":"Louis Delhaize"},"image":{"@id":"https:\/\/louisdelhaize.be\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/louisdelhaize.be\/nl\/wp-json\/wp\/v2\/pages\/2042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/louisdelhaize.be\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/louisdelhaize.be\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/louisdelhaize.be\/nl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/louisdelhaize.be\/nl\/wp-json\/wp\/v2\/comments?post=2042"}],"version-history":[{"count":4,"href":"https:\/\/louisdelhaize.be\/nl\/wp-json\/wp\/v2\/pages\/2042\/revisions"}],"predecessor-version":[{"id":10683,"href":"https:\/\/louisdelhaize.be\/nl\/wp-json\/wp\/v2\/pages\/2042\/revisions\/10683"}],"wp:attachment":[{"href":"https:\/\/louisdelhaize.be\/nl\/wp-json\/wp\/v2\/media?parent=2042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}